{"id":305,"date":"2015-10-23T13:59:20","date_gmt":"2015-10-23T11:59:20","guid":{"rendered":"http:\/\/www.geroborrmann.de\/wp\/?p=305"},"modified":"2016-01-22T21:56:26","modified_gmt":"2016-01-22T20:56:26","slug":"wirtschaftspruefung-in-der-rentenversicherung-2","status":"publish","type":"post","link":"http:\/\/www.geroborrmann.de\/wp\/2015\/10\/23\/wirtschaftspruefung-in-der-rentenversicherung-2\/","title":{"rendered":"Wirtschaftspr\u00fcfung in der Rentenversicherung"},"content":{"rendered":"<h2>ein Weg zu einer modernen (anderen?) Sozialversicherung?<\/h2>\n<p>Der Beitrag analysiert und bewertet m\u00f6gliche Ver\u00e4nderungsprozesse der selbstverwalteten vom Solidarit\u00e4tsprinzip gepr\u00e4gten Rentenversicherung unter dem Aspekt, wem die Einbeziehung der Wirtschaftspr\u00fcfer in den Haushaltskreislauf der Rentensicherung n\u00fctzt (cui bono?).<br \/>\n<em>Deutsche Rentenversicherung 2015.225ff.<\/em><\/p>\n<div class=\"wc-shortcodes-accordion wc-shortcodes-item wc-shortcodes-accordion-collapse wc-shortcodes-accordion-layout-box\" data-behavior=\"autoclose\" data-start-state=\"collapse\">\n<div class=\"wc-shortcodes-accordion-trigger \"><a href=\"#\">weiterlesen<\/a><\/div>\n<div class=\"wc-shortcodes-accordion-content-wrapper\">\n<div class=\"wc-shortcodes-accordion-content wc-shortcodes-content\">Der Beitrag f\u00fchrt in der Analyse der Interessenlage der Beteiligten zu folgenden Ergebnissen:<\/p>\n<ul>\n<li>Die \u00dcbertragung der Rechnungspr\u00fcfung auf Wirtschaftspr\u00fcfer steht im Kontext mit der Politik des New Public Management, die eine Ver\u00e4nderung des Selbstverst\u00e4ndnisses von einer hoheitlichen Verwaltung hin zu einer Dienstleistungsverwaltung mit privatwirtschaftlicher Managementmethoden sowie einen Einflussverlust der Selbstverwaltung beinhaltet.<\/li>\n<li>Die Rechnungspr\u00fcfung der Rentenversicherung passt nicht nur markterweiternd in die Strategie der Big4, weil ihnen durch EU Recht Aufgaben wegfallen, sondern ist auch Teil der Gesamtstrategie, Rechnungspr\u00fcfung und Beratung sowie das Rechnungswesen des \u00f6ffentlichen Sektors insgesamt durch nationale und internationale Aktivit\u00e4ten zu vereinnahmen.<\/li>\n<li>Es ist nicht ersichtlich, dass die Wirtschaftspr\u00fcfung das Rechnungswesen der Rentenversicherungstr\u00e4ger optimiert.<\/li>\n<li>Ein Weg zu einer modernen (anderen?) Sozialversicherung ist angelegt, wenn entsprechend der Empfehlung des BRH die Ministerien mit einer zentralistischen und die Big4 mit ihrer betriebswirtschaftlichen Orientierung st\u00e4rkeren Einfluss auf die Tr\u00e4ger der Rentenversicherung gewinnen; das derzeitige System sichert eine im Hinblick auf die generationen\u00fcbergreifende Aufgabe eine gewisse Staatsferne vom aktuellen tagespolitischen Politikgesch\u00e4ft und verwirklicht durch die Selbstverwaltung das Demokratieprinzip in der sozialen Sicherung.<\/li>\n<li>Die Stellung des BRH als Kontrollorgan d\u00fcrfte trotz verfassungsrechtlicher Fundierung angesichts des aggressiven und markterweiternden Vorgehen der Big4 langfristig nicht unber\u00fchrt bleiben. Die scheinbare Liberalisierung n\u00fctzt global agierenden Gro\u00dforganisationen und schw\u00e4cht den Staat in seiner generationen\u00fcbergreifenden Aufgabe in der Rentenversicherung.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ein Weg zu einer modernen (anderen?) Sozialversicherung? Der Beitrag analysiert und bewertet m\u00f6gliche Ver\u00e4nderungsprozesse der selbstverwalteten vom Solidarit\u00e4tsprinzip gepr\u00e4gten Rentenversicherung unter dem Aspekt, wem die Einbeziehung der Wirtschaftspr\u00fcfer in den Haushaltskreislauf der Rentensicherung n\u00fctzt (cui bono?). Deutsche Rentenversicherung 2015.225ff. weiterlesen Der Beitrag f\u00fchrt in der Analyse der Interessenlage der Beteiligten zu folgenden Ergebnissen: Die \u00dcbertragung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[128,9],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p722yw-4V","_links":{"self":[{"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/posts\/305"}],"collection":[{"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":7,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"predecessor-version":[{"id":315,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/posts\/305\/revisions\/315"}],"wp:attachment":[{"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.geroborrmann.de\/wp\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}